{"id":4523,"date":"2021-02-04T19:00:42","date_gmt":"2021-02-04T18:00:42","guid":{"rendered":"https:\/\/igualdad.us.es\/?p=4523"},"modified":"2021-02-04T19:02:11","modified_gmt":"2021-02-04T18:02:11","slug":"video-de-la-accion-poetica-atrapadas","status":"publish","type":"post","link":"https:\/\/igualdad.us.es\/wpblog\/video-de-la-accion-poetica-atrapadas\/","title":{"rendered":"V\u00eddeo de la acci\u00f3n po\u00e9tica ATRAPADAS"},"content":{"rendered":"\n<p>Si quieres ver el v\u00eddeo grabado de la acci\u00f3n po\u00e9tica <strong>ATRAPADAS<\/strong>, de <strong>Militancia Po\u00e9tica<\/strong>, que se ha elaborado de la actividad que hicimos el <strong>25 de noviembre <\/strong>de 2020, en la Facultad de Ciencias de la Educaci\u00f3n, con motivo del<strong> D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra las Mujeres<\/strong>, pulsa <span style=\"color: #993366;\"><a style=\"color: #993366;\" href=\"https:\/\/hdvirtual.us.es\/discovirt\/index.php\/s\/RQapHN6CRQ2kSjQ\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>del 25N, D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra las Mujeres<\/p>\n","protected":false},"author":1,"featured_media":4314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,39],"tags":[],"class_list":["post-4523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividad","category-actividad-propia"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts\/4523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/comments?post=4523"}],"version-history":[{"count":2,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts\/4523\/revisions"}],"predecessor-version":[{"id":4525,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts\/4523\/revisions\/4525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/media\/4314"}],"wp:attachment":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/media?parent=4523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/categories?post=4523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/tags?post=4523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}