{"id":2722,"date":"2019-10-17T09:59:56","date_gmt":"2019-10-17T09:59:56","guid":{"rendered":"http:\/\/igualdad.us.es\/?p=2722"},"modified":"2019-10-17T12:53:08","modified_gmt":"2019-10-17T12:53:08","slug":"2722","status":"publish","type":"post","link":"https:\/\/igualdad.us.es\/wpblog\/2722\/","title":{"rendered":"XII Encuentro Internacional Mujeres Singulares"},"content":{"rendered":"<p><span style=\"color: #993366;\"><strong>XII Encuentro Internacional Mujeres Singulares: Mujeres en la m\u00fasica. Ellas llevan la batuta<br \/>\n<\/strong><\/span><span style=\"color: #999999;\">(Colaboracion-Igualdad-2018)<\/span><\/p>\n<p style=\"text-align: justify;\">Con el objetivo de sacar a la luz mujeres relevantes de ayer que nos sirvan de referentes hoy. Y as\u00ed, a trav\u00e9s de diferentes y emblem\u00e1ticas figuras de la m\u00fasica, anhelamos recobrar no a una, sino a todas las mujeres singulares cuya dedicaci\u00f3n al arte de la m\u00fasica y sus variantes y\/o complementos, no han sido recompensadas debidamente. Todas ellas son merecedoras de nuestra gratitud y del reconocimiento acad\u00e9mico y social, pero, ninguna de ellas ha sido reconocidas como se merec\u00edan o como lo han hecho con sus cohetanos.<\/p>\n<p><strong>Organiza:<\/strong> Asociaci\u00f3n por los Derechos de las Mujeres Mar\u00eda Laffitte<br \/>\n<strong>Colabora:<\/strong><span class=\"texto_gris\"> Unidad para la Igualdad de la US<\/span><br \/>\n<strong>Realizaci\u00f3n:<\/strong> 23, 24 y 25 de octubre de 2019, de 9 a 14 h, en la Sede Olavide Centro \u2013 c\/ Lara\u00f1a- n\u00ba 4, segunda planta, Sevilla<strong><br \/>\nInscripci\u00f3n:<\/strong> gratuita hasta completar aforo, previa inscripci\u00f3n <a href=\"https:\/\/www.marialaffitte.org\/xii-encuentro-internacional-mujeres-singulares-mujeres-en-la-musica-ellas-llevan-la-batuta\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #993366;\">Aqu\u00ed<\/span><\/a><br \/>\n<strong>Publicidad: <\/strong><span style=\"color: #993366;\"><a style=\"color: #993366;\" href=\"https:\/\/igualdad.us.es\/wpblog\/wp-content\/uploads\/2019\/10\/XII-Encuentro-Inter-Mujeres-Singulares_Cartel.jpg\" target=\"_blank\" rel=\"noopener\">Cartel<\/a> &#8211; <a style=\"color: #993366;\" href=\"http:\/\/www.marialaffitte.org\/programa-xii-encuentro-internacional-mujeres-singulares-23-24-y-25-de-octubre-de-2019-2\/\" target=\"_blank\" rel=\"noopener\">Programa<\/a><\/span><br \/>\n<strong>+ Informaci\u00f3n:<\/strong>\u00a0 <a href=\"https:\/\/www.marialaffitte.org\/xii-encuentro-internacional-mujeres-singulares-mujeres-en-la-musica-ellas-llevan-la-batuta\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #993366;\">www.marialaffitte.org<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>23, 24 y 25 de octubre de 2019<\/p>\n","protected":false},"author":1,"featured_media":2723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,29,44,27],"tags":[],"class_list":["post-2722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividad","category-formacion","category-formacion-colaboracion","category-noticia"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts\/2722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/comments?post=2722"}],"version-history":[{"count":7,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts\/2722\/revisions"}],"predecessor-version":[{"id":2733,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/posts\/2722\/revisions\/2733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/media\/2723"}],"wp:attachment":[{"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/media?parent=2722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/categories?post=2722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/igualdad.us.es\/wpblog\/wp-json\/wp\/v2\/tags?post=2722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}